{"id":36785,"date":"2026-05-13T09:08:39","date_gmt":"2026-05-13T12:08:39","guid":{"rendered":"https:\/\/magistrarcursos.com.br\/blog\/?p=36785"},"modified":"2026-05-13T09:08:52","modified_gmt":"2026-05-13T12:08:52","slug":"concurso-tj-go-juiz-saiu-o-resultado-definitivo-da-prova-objetiva-e-convocacao-para-segunda-etapa","status":"publish","type":"post","link":"https:\/\/magistrarcursos.com.br\/blog\/concurso-tj-go-juiz-saiu-o-resultado-definitivo-da-prova-objetiva-e-convocacao-para-segunda-etapa\/","title":{"rendered":"Concurso TJ GO Juiz: saiu o resultado definitivo da prova objetiva e convoca\u00e7\u00e3o para segunda etapa!"},"content":{"rendered":"\n<p>O concurso do Tribunal de Justi\u00e7a do Estado de Goi\u00e1s (TJ GO) para o cargo de Juiz Substituto divulgou, atrav\u00e9s do Di\u00e1rio Oficial, o resultado definitivo da prova objetiva seletiva e tamb\u00e9m publicou a convoca\u00e7\u00e3o oficial para a segunda etapa do certame, que inclui as provas discursivas e pr\u00e1ticas de senten\u00e7a.<\/p>\n\n\n\n<p><a href=\"https:\/\/magistrarcursos.com.br\/blog\/wp-content\/uploads\/2026\/05\/resultado-definitivo-objetiva-tj-go-juiz.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Resultado definitivo da prova objetiva<\/strong><\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/magistrarcursos.com.br\/blog\/wp-content\/uploads\/2026\/05\/convocacao-2-etapa-tj-go-juiz.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Convoca\u00e7\u00e3o para a segunda etapa e lista de candidatos convocados<\/strong><\/a><\/p>\n\n\n\n<p>A segunda etapa ser\u00e1 composta por duas provas escritas: uma discursiva e outra pr\u00e1tica. A prova pr\u00e1tica ser\u00e1 dividida em dois dias, contemplando senten\u00e7a c\u00edvel e senten\u00e7a criminal.<\/p>\n\n\n\n<p>As avalia\u00e7\u00f5es ser\u00e3o aplicadas nas seguintes datas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Prova discursiva: <\/strong>31 de maio de 2026 (manh\u00e3); das 8h \u00e0s 12h<\/li>\n\n\n\n<li><strong>Prova pr\u00e1tica de senten\u00e7a c\u00edvel: <\/strong>31 de maio de 2026 (tarde); das 15h \u00e0s 20h<\/li>\n\n\n\n<li><strong>Prova pr\u00e1tica de senten\u00e7a criminal: <\/strong>1\u00ba de junho de 2026 (tarde); das 15h \u00e0s 20h<\/li>\n<\/ul>\n\n\n\n<p>Os candidatos convocados dever\u00e3o consultar o local de prova a partir do dia <strong>25 de maio de 2026<\/strong>, no <a href=\"https:\/\/conhecimento.fgv.br\/concursos\/tjgo2025\" target=\"_blank\" rel=\"noreferrer noopener\">portal da FGV<\/a>, mediante consulta individual.<\/p>\n\n\n\n<p>Os port\u00f5es ser\u00e3o fechados \u00e0s <strong>7h30 no turno da manh\u00e3 e \u00e0s 14h30 no per\u00edodo da tarde<\/strong>. Os candidatos devem comparecer com anteced\u00eancia m\u00ednima de uma hora, portando documento oficial de identidade, comprovante de inscri\u00e7\u00e3o e caneta esferogr\u00e1fica transparente de tinta azul ou preta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Concurso TJ GO Juiz<\/h2>\n\n\n\n<p>O <a href=\"https:\/\/magistrarcursos.com.br\/blog\/concurso-tjgo-juiz\/\" target=\"_blank\" rel=\"noreferrer noopener\">concurso TJ GO para Juiz Substituto<\/a> oferta <strong>51 vagas imediatas<\/strong>, al\u00e9m de cadastro de reserva. A remunera\u00e7\u00e3o inicial do cargo \u00e9 de <strong>R$ 34.083,41<\/strong>.<\/p>\n\n\n\n<p>Para concorrer ao cargo de Juiz Substituto do TJ GO, os candidatos devem possuir <strong>diploma de bacharel em Direito<\/strong>, comprovar <strong>tr\u00eas anos de atividade jur\u00eddica <\/strong>exercida ap\u00f3s a gradua\u00e7\u00e3o e possuir <strong>habilita\u00e7\u00e3o no <\/strong><a href=\"https:\/\/magistrarcursos.com.br\/blog\/enam-exame-nacional-magistratura\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Exame Nacional da Magistratura (ENAM)<\/strong><\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/t.magistrarcursos.com.br\/cerebro-juridico\/?utm_source=blog\" target=\"_blank\" rel=\" noreferrer noopener\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"237\" src=\"https:\/\/magistrarcursos.com.br\/blog\/wp-content\/uploads\/2026\/04\/banner-vitalicia-cerebro.webp\" alt=\"\" class=\"wp-image-34598\" srcset=\"https:\/\/magistrarcursos.com.br\/blog\/wp-content\/uploads\/2026\/04\/banner-vitalicia-cerebro.webp 800w, https:\/\/magistrarcursos.com.br\/blog\/wp-content\/uploads\/2026\/04\/banner-vitalicia-cerebro-300x89.webp 300w, https:\/\/magistrarcursos.com.br\/blog\/wp-content\/uploads\/2026\/04\/banner-vitalicia-cerebro-768x228.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Candidatos convocados j\u00e1 podem consultar os documentos oficiais; provas discursiva e de senten\u00e7a ser\u00e3o aplicadas entre os dias 31 de maio e 1\u00ba de junho<\/p>\n","protected":false},"author":13,"featured_media":35539,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,104],"tags":[],"class_list":["post-36785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-magistraturas"],"_links":{"self":[{"href":"https:\/\/magistrarcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/36785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magistrarcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/magistrarcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/magistrarcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/magistrarcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=36785"}],"version-history":[{"count":1,"href":"https:\/\/magistrarcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/36785\/revisions"}],"predecessor-version":[{"id":36786,"href":"https:\/\/magistrarcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/36785\/revisions\/36786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magistrarcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/35539"}],"wp:attachment":[{"href":"https:\/\/magistrarcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=36785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/magistrarcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=36785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/magistrarcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=36785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}